{"id":281562,"date":"2026-01-08T12:23:06","date_gmt":"2026-01-08T15:23:06","guid":{"rendered":"https:\/\/informaticala.udec.cl\/?p=281562"},"modified":"2026-01-23T12:30:47","modified_gmt":"2026-01-23T15:30:47","slug":"un-ejemplo-de-motivacion-ex-alumno-del-campus-los-angeles-acompano-como-docente-a-joven-puntaje-nacional-de-matematicas","status":"publish","type":"post","link":"https:\/\/informaticala.udec.cl\/index.php\/2026\/01\/08\/un-ejemplo-de-motivacion-ex-alumno-del-campus-los-angeles-acompano-como-docente-a-joven-puntaje-nacional-de-matematicas\/","title":{"rendered":"Un ejemplo de motivaci\u00f3n: Ex alumno del Campus Los \u00c1ngeles acompa\u00f1\u00f3 como docente a joven puntaje nacional de Matem\u00e1ticas"},"content":{"rendered":"\n\n\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-a205ea7fbd1f014ed21af11e29c00c8c\"><em>La historia de Felipe Lonconao R\u00edos y su profesor Jaime Molina Flores sembraron el deseo de superaci\u00f3n en decenas de estudiantes que siguieron su logro.<\/em><\/p>\n\n\n\n<p>Con perfectos mil puntos en la prueba de Matem\u00e1tica correspondiente a la Prueba de Acceso a la Educaci\u00f3n Superior PAES despert\u00f3 el pasado domingo Felipe Lonconao R\u00edos.<\/p>\n\n\n\n<p>Su historia refleja que la constancia y el compromiso sin duda llevan a cumplir los sue\u00f1os, m\u00e1s a\u00fan cuando hay personas que apoyan y colaboran en el camino. De aquello sabe el egresado de Pedagog\u00eda en Matem\u00e1ticas del Campus Los \u00c1ngeles de la Universidad de Concepci\u00f3n, el profesor Jaime Molina Flores.<\/p>\n\n\n\n<p><strong>Una se\u00f1al previa<\/strong><\/p>\n\n\n\n<p>Felipe hab\u00eda manifestado desde sus primeros a\u00f1os de ense\u00f1anza media la intenci\u00f3n de ser puntaje nacional. Como estudiante del Liceo Bicentenario de Excelencia Nuevo Mundo de Mulch\u00e9n ten\u00eda una meta clara: desayunar en La Moneda con el presidente tras rendir la PAES.<\/p>\n\n\n\n<p>\u201c\u00c9l era un estudiante muy comprometido, era un estudiante que ten\u00eda la iniciativa, ten\u00eda ganas de seguir adelante, ten\u00eda ganas de lograr algo y ten\u00eda intenci\u00f3n de lograr un puntaje m\u00e1ximo y recibir el galard\u00f3n de poder desayunar con el presidente en La Moneda. Entonces ten\u00eda ese deseo, quer\u00eda obtener ese logro\u201d, recuerda un emocionado Jaime, profesor que lo acompa\u00f1\u00f3 en este desaf\u00edo.<\/p>\n\n\n\n<p>Sin embargo, hubo algunos obst\u00e1culos que marcaron su etapa, siendo el mayor de ellos los nervios de cumplir con el objetivo trazado. En segundo medio comenz\u00f3 a participar de talleres, mientras que el trabajo m\u00e1s intenso parti\u00f3 en tercero medio, cuando se hizo parte del preuniversitario que se dictaba por su establecimiento.<\/p>\n\n\n\n<p>Los n\u00fameros iniciales en esta historia eran de 600 puntos, cifra que poco a poco se fue modificando con la constancia y esfuerzo de Felipe, quien de 17:30 a 19:00 horas se dedicaba en su totalidad a preparar su prueba, en un espacio facilitado por la municipalidad para llevar a cabo sus estudios complementarios.<\/p>\n\n\n\n<p>Jaime, su profesor, recuerda uno de los \u00faltimos ensayos que entreg\u00f3, y que estuvo marcado por el nerviosismo de Felipe. \u201cLleg\u00f3 a hacer ese ensayo y estaba muy nervioso. Me dijo profesor rev\u00edselo al tiro, por favor. Yo lo not\u00e9 nervios\u00edsimo y le dije \u00bfpor qu\u00e9 est\u00e1s tan nervioso, si se trata de un ensayo? Porque creo que lo tengo todo bueno, me respondi\u00f3\u201d.<\/p>\n\n\n\n<p>Fue aquella prueba de pr\u00e1ctica que le demostr\u00f3 a ambos lo que estaban consiguiendo: la totalidad del puntaje en la prueba. \u201cYo se lo revis\u00e9 y efectivamente ten\u00eda todo bueno, ten\u00eda mil puntos en un ensayo, entonces era la primera vez que \u00e9l lograba llegar a eso y de ah\u00ed para all\u00e1 el problema que tuvimos que enfrentar era su sistema nervioso\u201d, manifest\u00f3 el docente.<\/p>\n\n\n\n<p>Con aquel desaf\u00edo detectado, el trabajo no se centr\u00f3 solo en la preparaci\u00f3n de los estudios, sino que tambi\u00e9n en lo emocional y mental. Fueron extensas conversaciones en las que le hac\u00eda sentir confianza, en donde se le motivaba a no rendirse, y por sobre todo, a confiar en \u00e9l mismo.<\/p>\n\n\n\n<p><strong>Una motivaci\u00f3n para los dem\u00e1s<\/strong><\/p>\n\n\n\n<p>El ejemplo de Felipe ha cautivado tanto a la comuna de Mulch\u00e9n como a la Provincia de Biob\u00edo. Su historia de esfuerzo y constancia ha demostrado la capacidad de lograr los sue\u00f1os, a\u00fan cuando existan dificultades en el camino.<\/p>\n\n\n\n<p>Esto, para el egresado del Campus Los \u00c1ngeles, es tambi\u00e9n un ejemplo para m\u00e1s estudiantes, ya que \u201clos dem\u00e1s profesores nos comentaban que sus estudiantes les dec\u00edan profe, yo igual quiero ser puntaje nacional\u201d.<\/p>\n\n\n\n<p>Y aquella motivaci\u00f3n no queda solo para las y los alumnos que siguen en su ense\u00f1anza media, sino que tambi\u00e9n para las y los docentes que hoy ejercen, como tambi\u00e9n quienes se est\u00e1n formando para el d\u00eda de ma\u00f1ana transformar vidas como fue este caso.<\/p>\n\n\n\n<p>\u201cEs importante no olvidar que trabajamos con personas que sienten, que tienen emociones, y que a veces no tienen energ\u00eda o est\u00e1n cansados. Entonces, como profe debes prepararte y tener la fortaleza de que, incluso tambi\u00e9n cansado, puedas darles tu apoyo, energ\u00eda, y transmitirles confianza\u201d, sentenci\u00f3 Molina.<\/p>\n\n\n\n<p>De este modo, afirm\u00f3 que esta historia sin duda es un precedente tanto para el establecimiento como para la comunidad, y que revela que con entusiasmo y apoyo se pueden conseguir grandes cosas, como lo demostr\u00f3 Felipe, que obtuvo mil puntos en la PAES, y logr\u00f3 desayunar en La Moneda con el presidente Gabriel Boric.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"644\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-2-960x644-1.jpeg\" alt=\"\" class=\"wp-image-281563\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-2-960x644-1.jpeg 960w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-2-960x644-1-480x322.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 960px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a980132d0893&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a980132d0893\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"281564\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-1-768x1024.jpeg\" alt=\"\" class=\"wp-image-281564\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-1-768x1024.jpeg 768w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-1-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a980132d1a97&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a980132d1a97\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"281565\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-281565\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-2-768x1024.jpeg 768w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-2-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a980132d2b3c&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a980132d2b3c\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"281566\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-3-768x1024.jpeg\" alt=\"\" class=\"wp-image-281566\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-3-768x1024.jpeg 768w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-3-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a980132d3bb4&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a980132d3bb4\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"281567\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-4-768x1024.jpeg\" alt=\"\" class=\"wp-image-281567\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-4-768x1024.jpeg 768w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-4-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a980132d4dbe&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a980132d4dbe\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"582\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"281568\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-5-582x1024.jpeg\" alt=\"\" class=\"wp-image-281568\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-5-582x1024.jpeg 582w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/01\/Felipe-PAES-5-480x844.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 582px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La historia de Felipe Lonconao R\u00edos y su profesor Jaime Molina Flores sembraron el deseo de superaci\u00f3n en decenas de estudiantes que siguieron su logro. Con perfectos mil puntos en [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":281563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-281562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts\/281562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/comments?post=281562"}],"version-history":[{"count":1,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts\/281562\/revisions"}],"predecessor-version":[{"id":281569,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts\/281562\/revisions\/281569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/media\/281563"}],"wp:attachment":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/media?parent=281562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/categories?post=281562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/tags?post=281562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}