{"id":282754,"date":"2025-06-10T15:50:00","date_gmt":"2025-06-10T18:50:00","guid":{"rendered":"https:\/\/informaticala.udec.cl\/?p=282754"},"modified":"2026-03-19T15:53:46","modified_gmt":"2026-03-19T18:53:46","slug":"taller-sobre-ciclo-menstrual-para-estudiantes-promueve-el-autocuidado-y-la-educacion-en-salud-sexual-en-el-campus-los-angeles","status":"publish","type":"post","link":"https:\/\/informaticala.udec.cl\/index.php\/2025\/06\/10\/taller-sobre-ciclo-menstrual-para-estudiantes-promueve-el-autocuidado-y-la-educacion-en-salud-sexual-en-el-campus-los-angeles\/","title":{"rendered":"Taller sobre ciclo menstrual para estudiantes promueve el autocuidado y la educaci\u00f3n en salud sexual en el Campus Los \u00c1ngeles"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Con una alta participaci\u00f3n estudiantil se realiz\u00f3 en el Campus Los \u00c1ngeles de la Universidad de Concepci\u00f3n el taller \u201cSalud Menstrual\u201d, una actividad impulsada por la Unidad de Salud de la Direcci\u00f3n de Servicios Estudiantiles (DISE), del Campus Los&nbsp;&nbsp;\u00c1ngeles, orientada a promover la educaci\u00f3n, el autocuidado y la desmitificaci\u00f3n de creencias en torno a la menstruaci\u00f3n.<\/p>\n\n\n\n<p>La iniciativa forma parte de una serie de acciones que buscan acercar contenidos de salud sexual y reproductiva al estudiantado, desde una perspectiva integral, inclusiva y educativa. Durante el taller, la matrona Paula Villalobos abord\u00f3 temas fundamentales como las fases del ciclo menstrual, los cambios hormonales que ocurren en cada etapa, el uso correcto de insumos menstruales y los mitos que a\u00fan persisten en torno a este proceso natural.<\/p>\n\n\n\n<p>\u201cEl objetivo principal del taller fue educar sobre el ciclo menstrual de una forma clara, precisa y comprensible para las estudiantes. Queremos que entiendan bien las fases del ciclo, los cambios que ocurren por efecto de las hormonas y, sobre todo, derribar muchos de los mitos que a\u00fan existen. La idea tambi\u00e9n fue entregar herramientas de autocuidado y ense\u00f1ar sobre los distintos insumos menstruales, c\u00f3mo usarlos correctamente y qu\u00e9 tener en cuenta al momento de elegirlos\u201d, se\u00f1al\u00f3 Paula Villalobos.<\/p>\n\n\n\n<p>En esa misma l\u00ednea, la profesional destac\u00f3 que muchas creencias err\u00f3neas siguen presentes en la cultura y es necesario abordarlas desde la evidencia y la informaci\u00f3n confiable.<\/p>\n\n\n\n<p>\u201cUno de los prop\u00f3sitos m\u00e1s importantes del taller fue hablar de todos esos mitos que, aunque parezcan antiguos, todav\u00eda siguen circulando. Por ejemplo, muchas escucharon que no se puede uno ba\u00f1ar durante la menstruaci\u00f3n, o que, si no llega un mes, la sangre queda retenida en el cuerpo y eso ser\u00eda malo. Eso no es cierto. Tambi\u00e9n existe la creencia de que todas las menstruaciones son iguales, pero incluso en una misma persona puede cambiar de mes a mes. Todo eso es normal y es parte del conocimiento que quer\u00edamos compartir.\u201d<\/p>\n\n\n\n<p>La actividad fue bien recibida por las asistentes, quienes valoraron el espacio como una instancia de aprendizaje y conversaci\u00f3n en un ambiente cercano y respetuoso.<\/p>\n\n\n\n<p>\u201cEl taller me gust\u00f3 mucho, fue una experiencia s\u00faper buena y entretenida. La matrona explic\u00f3 todo de forma muy clara y cercana, as\u00ed que se entendi\u00f3 perfecto. Adem\u00e1s, logr\u00f3 que el ambiente fuera s\u00faper agradable. Espero poder tener m\u00e1s instancias como estas, ya que sirve mucho para informarnos y tambi\u00e9n despejarnos\u201d, coment\u00f3 la estudiante Constanza Neira.<\/p>\n\n\n\n<p>Desde la Direcci\u00f3n de Servicios Estudiantiles del Campus Los \u00c1ngeles, su jefa, Jeannette Parra, reafirm\u00f3 el compromiso de la unidad con la promoci\u00f3n de la salud integral del estudiantado.<\/p>\n\n\n\n<p>\u201cDesde todas las \u00e1reas que componen nuestra unidad, trabajamos con un enfoque claro: promover el bienestar y la salud integral de nuestros estudiantes. En el \u00e1mbito de la salud sexual, esto implica entregar informaci\u00f3n accesible, transversal y sin distinci\u00f3n de g\u00e9nero, para fomentar el autocuidado y la prevenci\u00f3n. Queremos que las y los estudiantes sepan que en nuestra unidad pueden acceder a orientaci\u00f3n, controles con matrona, realizaci\u00f3n de ex\u00e1menes como el PAP, elecci\u00f3n informada de m\u00e9todos anticonceptivos y tambi\u00e9n acompa\u00f1amiento en temas como el manejo del dolor menstrual.\u201d<\/p>\n\n\n\n<p>Adem\u00e1s, la jefa, destac\u00f3 que este taller es solo el inicio de una serie de actividades programadas para los pr\u00f3ximos meses.<\/p>\n\n\n\n<p>\u201cEn junio realizaremos una jornada educativa sobre VIH. En paralelo, estamos trabajando articuladamente con los Cesfam y el hospital local, a trav\u00e9s de charlas, instancias de educaci\u00f3n y entrega de insumos. Por eso, invitamos a nuestras y nuestros estudiantes a estar atentos a las redes oficiales del campus: existen espacios reales de apoyo, cuidados y orientaci\u00f3n pensados especialmente para ellos en esta etapa de sus vidas.\u201d<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571fefa96dd&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571fefa96dd\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"966\" height=\"644\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"282767\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7336-966x644-1.jpeg\" alt=\"\" class=\"wp-image-282767\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7336-966x644-1.jpeg 966w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7336-966x644-1-480x320.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 966px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571fefaa967&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571fefaa967\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"282768\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7331-1024x768.jpeg\" alt=\"\" class=\"wp-image-282768\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7331-980x735.jpeg 980w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7331-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571fefababd&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571fefababd\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"282765\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7332-1024x768.jpeg\" alt=\"\" class=\"wp-image-282765\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7332-980x735.jpeg 980w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7332-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571fefacced&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571fefacced\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"282769\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7334-1024x768.jpeg\" alt=\"\" class=\"wp-image-282769\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7334-980x735.jpeg 980w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7334-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571fefadd26&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571fefadd26\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"282770\" src=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7335-1024x768.jpeg\" alt=\"\" class=\"wp-image-282770\" srcset=\"https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7335-980x735.jpeg 980w, https:\/\/informaticala.udec.cl\/wp-content\/uploads\/2026\/03\/IMG_7335-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con una alta participaci\u00f3n estudiantil se realiz\u00f3 en el Campus Los \u00c1ngeles de la Universidad de Concepci\u00f3n el taller \u201cSalud Menstrual\u201d, una actividad impulsada por la Unidad de Salud de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":282769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7],"tags":[48,19,49],"class_list":["post-282754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-los-angeles-2","tag-udec","tag-universidad-de-concepcion"],"_links":{"self":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts\/282754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/comments?post=282754"}],"version-history":[{"count":1,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts\/282754\/revisions"}],"predecessor-version":[{"id":282771,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/posts\/282754\/revisions\/282771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/media\/282769"}],"wp:attachment":[{"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/media?parent=282754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/categories?post=282754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informaticala.udec.cl\/index.php\/wp-json\/wp\/v2\/tags?post=282754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}